{"id":839,"date":"2026-05-08T14:38:28","date_gmt":"2026-05-08T06:38:28","guid":{"rendered":"https:\/\/www.jienmarine.com\/?post_type=products&#038;p=839"},"modified":"2026-05-08T15:13:04","modified_gmt":"2026-05-08T07:13:04","slug":"tiger-striped-rope","status":"publish","type":"products","link":"https:\/\/www.jienmarine.com\/es\/products\/tiger-striped-rope\/","title":{"rendered":"Cuerda rayada de tigre"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Proceso de producci\u00f3n<\/span><\/p>\n<div class=\"adweb-template\">\n<div class=\"adweb-template-40\">\n<div class=\"adweb-flex-jc-sb adweb-text-align-c adweb-position-title adweb-scale\">\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_10.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Tejido 1<\/p>\n<\/div>\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_12.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Tejido del producto<\/p>\n<\/div>\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_14.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Fabricaci\u00f3n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"adweb-template\">\n<div class=\"adweb-template-40\">\n<div class=\"adweb-flex-jc-sb adweb-text-align-c adweb-position-title adweb-scale\">\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_16.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Tejido del producto<\/p>\n<\/div>\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_18.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Apilado de productos terminados<\/p>\n<\/div>\n<div class=\"adweb-flex-item3 adweb-flex-item\">\n<div class=\"adweb-item-img\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jienmarine.com\/wp-content\/uploads\/2026\/05\/9c51036abc154ee8887656859a7d3427_20.jpg\" alt=\"\" width=\"600\" height=\"450\" data-no-translation=\"\" \/><\/div>\n<p>Apilado de productos terminados<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>Est\u00e1ndares de producci\u00f3n<\/strong>: EN 1492-2+A1, JB\/T8521-2007<\/p>\n<p><strong>Color<\/strong>: Cumple con est\u00e1ndares internacionales<\/p>\n<p>Ofrecemos tanto tubos para eslingas como productos terminados a la venta.<\/p>","protected":false},"featured_media":840,"template":"","adweb_product_categories":[19],"adweb_product_tags":[95],"class_list":["post-839","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-slings-and-rope-series","adweb_product_tag-tiger-striped-rope"],"gallery":[843,842,841],"order":null,"acf":[],"_links":{"self":[{"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/adweb_products\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/media\/840"}],"wp:attachment":[{"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/adweb_product_categories?post=839"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/www.jienmarine.com\/es\/wp-json\/wp\/v2\/adweb_product_tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}